{"id":7093,"date":"2019-07-03T18:34:10","date_gmt":"2019-07-03T16:34:10","guid":{"rendered":"https:\/\/nevcoaching.com\/?page_id=7093"},"modified":"2021-10-26T16:55:14","modified_gmt":"2021-10-26T14:55:14","slug":"leadership-excellence-school","status":"publish","type":"page","link":"https:\/\/nevcoaching.com\/es\/formacion\/leadership-excellence-school\/","title":{"rendered":"Leadership Excellence School"},"content":{"rendered":"[vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb60&#8243; bottom_padding=\u00bb40&#8243; text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][image_with_animation image_url=\u00bb8009&#8243; animation=\u00bbFade In\u00bb hover_animation=\u00bbnone\u00bb alignment=\u00bbcenter\u00bb img_link_large=\u00bbyes\u00bb border_radius=\u00bbnone\u00bb box_shadow=\u00bbnone\u00bb image_loading=\u00bbdefault\u00bb max_width=\u00bb75%\u00bb max_width_mobile=\u00bbdefault\u00bb el_class=\u00bbimage-width-100&#8243; margin_bottom=\u00bb50&#8243;][vc_column_text css=\u00bb.vc_custom_1562171844567{margin-bottom: 50px !important;}\u00bb]\n<p style=\"text-align: center;\">Hay muchas formaciones en Liderazgo hoy d\u00eda pero incluso las de las m\u00e1s altas instituciones, carecen de <span style=\"color: #425cc7;\">un programa y tratamiento debidamente personalizado<\/span>, de un <span style=\"color: #425cc7;\">seguimiento para asegurar los resultados<\/span> y de una experiencia realmente profunda, amena y divertida.<\/p>\n<p style=\"text-align: center;\">Pero nuestra nueva <span style=\"color: #425cc7;\"><strong>Leadership Excellence School<\/strong><\/span> es todo lo contrario.<\/p>\n<p style=\"text-align: center;\">Despu\u00e9s de a\u00f1os de \u00e9xito en este campo, cientos de clientes exitosos y peticiones para este tipo de programa, hemos creado una <span style=\"color: #425cc7;\">experiencia realmente completa, innovadora e impactante<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #425cc7;\"><strong>\u2026para TI.<\/strong><\/span><\/p>\n[\/vc_column_text][image_with_animation image_url=\u00bb8011&#8243; animation=\u00bbFade In\u00bb hover_animation=\u00bbnone\u00bb alignment=\u00bbcenter\u00bb img_link_large=\u00bbyes\u00bb border_radius=\u00bbnone\u00bb box_shadow=\u00bbnone\u00bb image_loading=\u00bbdefault\u00bb max_width=\u00bb75%\u00bb max_width_mobile=\u00bbdefault\u00bb el_class=\u00bbimage-width-100&#8243; margin_bottom=\u00bb50&#8243;][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bottom_padding=\u00bb50&#8243; text_align=\u00bbleft\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/nevcoaching.com\/wp-content\/uploads\/2019\/07\/arrow-e1544542880998-150x150.jpg\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> <span style=\"color: #425cc7;\"><strong>Empresarios\/as<\/strong> de empresas PYMES o grandes<\/span>, que quieren alcanzar su mayor efectividad como l\u00edderes excepcionales para su organizaci\u00f3n. <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/nevcoaching.com\/wp-content\/uploads\/2019\/07\/arrow-e1544542880998-150x150.jpg\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> <span style=\"color: #425cc7;\"><strong>Directivos<\/strong> de cualquier nivel<\/span> que reconocen que su liderazgo es la mayor contribuci\u00f3n que pueden ofrecer y optimizar, para el bien de su empresa y su carrera profesional. <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/nevcoaching.com\/wp-content\/uploads\/2019\/07\/arrow-e1544542880998-150x150.jpg\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> <span style=\"color: #425cc7;\"><strong>Emprendedores<\/strong> de empresas buscando el \u00e9xito de largo plazo<\/span>, intentando pasar al nivel de excelencia necesario para tener un negocio realmente sostenible e impactante. <\/div><div class=\"clear\"><\/div><\/div>[\/vc_column_inner][\/vc_row_inner][image_with_animation image_url=\u00bb7101&#8243; animation=\u00bbFade In\u00bb hover_animation=\u00bbnone\u00bb alignment=\u00bbcenter\u00bb img_link_target=\u00bb_blank\u00bb border_radius=\u00bbnone\u00bb box_shadow=\u00bbnone\u00bb image_loading=\u00bbdefault\u00bb max_width=\u00bb100%\u00bb max_width_mobile=\u00bbdefault\u00bb margin_bottom=\u00bb50&#8243; img_link=\u00bbhttps:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSeHoQ8lwwodeObpyaQ8MvssBFD-CPrgv1lZ2zUDmlqQejn3Qw\/viewform\u00bb el_class=\u00bblider-img\u00bb][image_with_animation image_url=\u00bb8013&#8243; animation=\u00bbFade In\u00bb hover_animation=\u00bbnone\u00bb alignment=\u00bbcenter\u00bb img_link_large=\u00bbyes\u00bb border_radius=\u00bbnone\u00bb box_shadow=\u00bbnone\u00bb image_loading=\u00bbdefault\u00bb max_width=\u00bb75%\u00bb max_width_mobile=\u00bbdefault\u00bb margin_bottom=\u00bb80&#8243; el_class=\u00bbimage-width-100&#8243;][vc_column_text css=\u00bb.vc_custom_1562172660451{margin-bottom: 50px !important;}\u00bb]Nosotros ofrecemos un <span style=\"color: #425cc7;\">programa realmente completo<\/span>, innovador y ameno:[\/vc_column_text][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bottom_padding=\u00bb50&#8243; text_align=\u00bbleft\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/nevcoaching.com\/wp-content\/uploads\/2019\/07\/Diapositiva01-300x225-300x225.jpg\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> <span style=\"color: #425cc7;\"><strong>Formaci\u00f3n<\/strong> de la m\u00e1s alta calidad<\/span>, de las universidades m\u00e1s punteras de EEUU y 20+ a\u00f1os de experiencia internacional (8 sesiones \/ 64 horas). <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/nevcoaching.com\/wp-content\/uploads\/2019\/07\/Diapositiva02-300x225-300x225.jpg\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> <span style=\"color: #425cc7;\"><strong>Coaching ejecutivo<\/strong> probado y premiado<\/span>, para asegurar un desarrollo profundo y personalizado de cada L\u00edder (20 sesiones \/ hasta 40 horas). <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/nevcoaching.com\/wp-content\/uploads\/2019\/07\/Diapositiva03-300x225-300x225.jpg\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> <span style=\"color: #425cc7;\"><strong>Plan de Liderazgo <\/strong>a medida de cada l\u00edder<\/span>, asegurando su desarrollo y compromiso, con seguimiento y medici\u00f3n de su progreso. <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/nevcoaching.com\/wp-content\/uploads\/2019\/07\/Diapositiva04-300x225-300x225.jpg\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> <span style=\"color: #425cc7;\"><strong>Apoyo virtual<\/strong> durante un a\u00f1o<\/span>, para asegurar un servicio de cliente realmente atento y comprometido. <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/nevcoaching.com\/wp-content\/uploads\/2019\/07\/Diapositiva05-300x225-300x225.jpg\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> <span style=\"color: #425cc7;\"><strong>Pack de Formaci\u00f3n<\/strong> de todas las lecciones<\/span> como gu\u00eda de mejores pr\u00e1cticas para la futura aplicaci\u00f3n. <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/nevcoaching.com\/wp-content\/uploads\/2019\/07\/Diapositiva06-300x225-300x225.jpg\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> <span style=\"color: #425cc7;\"><strong>Libro de contenidos<\/strong> de trabajos y ejercicios<\/span> para facilitar su \u00f3ptimo desarrollo y progreso y para servir como referencia en futuros retos. <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/nevcoaching.com\/wp-content\/uploads\/2019\/07\/Diapositiva07-300x225-300x225.jpg\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> <span style=\"color: #425cc7;\">Recomendaciones de <strong>Recursos clave<\/strong><\/span> para profundizar el aprendizaje y asegurar un mayor ajuste a las necesidades de cada L\u00edder. <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/nevcoaching.com\/wp-content\/uploads\/2019\/07\/Diapositiva08-300x225-300x225.jpg\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> <span style=\"color: #425cc7;\"><strong>Certificado de Cumplimiento<\/strong><\/span> para justificar la dedicaci\u00f3n y el compromiso de cada L\u00edder. <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/nevcoaching.com\/wp-content\/uploads\/2019\/07\/Diapositiva09-300x225-300x225.jpg\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> <span style=\"color: #425cc7;\">Comidas, caf\u00e9s y otros beneficios<\/span>, durante las formaciones, para asegurar una experiencia realmente placentera, creativa e inspiradora. <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/nevcoaching.com\/wp-content\/uploads\/2019\/07\/Diapositiva10-300x225-300x225.jpg\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> <span style=\"color: #425cc7;\">Descuento para futuras iniciativas<\/span> durante un a\u00f1o para facilitar su continuo desarrollo y el de sus<br \/>\nequipos y organizaci\u00f3n. <\/div><div class=\"clear\"><\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_column_text css=\u00bb.vc_custom_1579181856297{margin-bottom: 50px !important;}\u00bb]\n<p style=\"text-align: center;\">Adem\u00e1s incluye otras ventajas, sobre todo que <span style=\"color: #425cc7;\">las formaciones ser\u00e1n en nuestras amenas instalaciones de Bermeo3<\/span>, para tu mayor comodidad y relajaci\u00f3n.<\/p>\n[\/vc_column_text][image_with_animation image_url=\u00bb7120&#8243; animation=\u00bbFade In\u00bb hover_animation=\u00bbnone\u00bb alignment=\u00bbcenter\u00bb img_link_target=\u00bb_blank\u00bb border_radius=\u00bbnone\u00bb box_shadow=\u00bbnone\u00bb image_loading=\u00bbdefault\u00bb max_width=\u00bb100%\u00bb max_width_mobile=\u00bbdefault\u00bb margin_bottom=\u00bb50&#8243; img_link=\u00bbhttp:\/\/bermeo3.com\/\u00bb][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#e5efff\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb30&#8243; text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb top_margin=\u00bb40&#8243; column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_custom_heading text=\u00bbPrograma Completo\u00bb font_container=\u00bbtag:h2|font_size:37px|text_align:left|color:%23425cc7&#8243; use_theme_fonts=\u00bbyes\u00bb css_animation=\u00bbnone\u00bb css=\u00bb.vc_custom_1562173679446{margin-bottom: 10px !important;}\u00bb][vc_column_text css=\u00bb.vc_custom_1562173689396{margin-bottom: 20px !important;}\u00bb]Pincha aqu\u00ed para leer el PROGRAMA COMPLETO.[\/vc_column_text][nectar_btn size=\u00bbjumbo\u00bb open_new_tab=\u00bbtrue\u00bb button_style=\u00bbregular\u00bb button_color_2=\u00bbAccent-Color\u00bb color_override=\u00bb#ec456a\u00bb icon_family=\u00bbnone\u00bb el_class=\u00bbbutton-normal\u00bb url=\u00bb\/wp-content\/uploads\/2020\/01\/Leadership-Excellence-School-NEV-CC-_ESP.pdf\u00bb text=\u00bbVer programa\u00bb][\/vc_column][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][image_with_animation image_url=\u00bb7124&#8243; animation=\u00bbNone\u00bb hover_animation=\u00bbnone\u00bb alignment=\u00bbcenter\u00bb img_link_target=\u00bb_blank\u00bb border_radius=\u00bbnone\u00bb box_shadow=\u00bbnone\u00bb image_loading=\u00bbdefault\u00bb max_width=\u00bb100%\u00bb max_width_mobile=\u00bbdefault\u00bb img_link=\u00bb\/wp-content\/uploads\/2020\/01\/Leadership-Excellence-School-NEV-CC-_ESP.pdf\u00bb][\/vc_column][\/vc_row][vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb50&#8243; text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][image_with_animation image_url=\u00bb8007&#8243; animation=\u00bbFade In\u00bb hover_animation=\u00bbnone\u00bb alignment=\u00bbcenter\u00bb img_link_large=\u00bbyes\u00bb border_radius=\u00bbnone\u00bb box_shadow=\u00bbnone\u00bb image_loading=\u00bbdefault\u00bb max_width=\u00bb75%\u00bb max_width_mobile=\u00bbdefault\u00bb margin_bottom=\u00bb80&#8243; el_class=\u00bbimage-width-100&#8243;][vc_column_text css=\u00bb.vc_custom_1580721151456{margin-bottom: 50px !important;}\u00bb]\n<p style=\"text-align: center;\">Para asegurar un acompa\u00f1amiento realmente completo, cari\u00f1oso y de la m\u00e1s alta confianza y conocimiento, tan solo podemos trabajar con unos pocos L\u00edderes cada temporada.<\/p>\n<ul>\n<li>El periodo de <span style=\"color: #425cc7;\"><strong>matriculaci\u00f3n se cerrar\u00e1 el 12 de septiembre 2020<\/strong><\/span>.<\/li>\n<li>La <span style=\"color: #425cc7;\"><strong>escuela<\/strong><\/span> (formaci\u00f3n + coaching) <span style=\"color: #425cc7;\">ser\u00e1 realizar\u00e1 a lo largo de un a\u00f1o<\/span> (8 talleres durante el a\u00f1o \/ sesiones de coaching individual seg\u00fan la disponibilidad de cada cliente).<\/li>\n<li><span style=\"color: #425cc7;\"><strong>15% descuento por cada matr\u00edcula<\/strong><\/span> si te inscribes con un compa\u00f1ero (m\u00e1ximo 2 personas).<\/li>\n<\/ul>\n<p style=\"text-align: center;\">As\u00ed que, si <span style=\"color: #425cc7;\">es tu momento de transformar tu liderazgo<\/span> para el bien de tu vida, tu trabajo y tu organizaci\u00f3n, <a href=\"\/acerca-de\/contactenos\/\"><strong>cont\u00e1ctanos aqu\u00ed<\/strong><\/a> o a <a href=\"mailto:nev@nevcoaching.com\">nev@nevcoaching.com<\/a> para m\u00e1s detalles.<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #425cc7;\">Este es tu momento, para TRIUNFAR.<\/span><\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb equal_height=\u00bbyes\u00bb content_placement=\u00bbmiddle\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#63cfe3&#8243; scene_position=\u00bbcenter\u00bb top_padding=\u00bb60&#8243; bottom_padding=\u00bb40&#8243; text_color=\u00bbdark\u00bb text_align=\u00bbcenter\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb enable_gradient=\u00bbtrue\u00bb color_overlay=\u00bb#425cc7&#8243; color_overlay_2=\u00bb#63cfe3&#8243; overlay_strength=\u00bb1&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb centered_text=\u00bbtrue\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_custom_heading text=\u00bb\u00a1Quiero Inscribirme!\u00bb font_container=\u00bbtag:h2|font_size:37px|text_align:center|color:%23ffffff\u00bb use_theme_fonts=\u00bbyes\u00bb css_animation=\u00bbnone\u00bb css=\u00bb.vc_custom_1562174795381{margin-bottom: 20px !important;}\u00bb][nectar_btn size=\u00bbjumbo\u00bb open_new_tab=\u00bbtrue\u00bb button_style=\u00bbregular\u00bb button_color_2=\u00bbAccent-Color\u00bb color_override=\u00bb#ec456a\u00bb icon_family=\u00bbnone\u00bb el_class=\u00bbbutton-border-white\u00bb button_id=\u00bbbutton-inscribete\u00bb url=\u00bbhttps:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSeHoQ8lwwodeObpyaQ8MvssBFD-CPrgv1lZ2zUDmlqQejn3Qw\/viewform\u00bb text=\u00bbInscr\u00edbete aqu\u00ed\u00bb margin_top=\u00bb20px\u00bb][\/vc_column][\/vc_row][vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][nectar_global_section id=\u00bb11597&#8243;][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#e5efff\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb30&#8243; text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb disable_element=\u00bbyes\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb top_margin=\u00bb40&#8243; column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_custom_heading text=\u00bbDossier NEV C&amp;C\u00bb font_container=\u00bbtag:h2|font_size:37px|text_align:left|color:%23425cc7&#8243; use_theme_fonts=\u00bbyes\u00bb css_animation=\u00bbnone\u00bb css=\u00bb.vc_custom_1560449793971{margin-bottom: 10px !important;}\u00bb][vc_column_text css=\u00bb.vc_custom_1564484039745{margin-bottom: 20px !important;}\u00bb]Descarga la historia de nuestra visi\u00f3n, servicios, especialidades y testimonios de valorados clientes.[\/vc_column_text][nectar_btn size=\u00bbjumbo\u00bb open_new_tab=\u00bbtrue\u00bb button_style=\u00bbsee-through-3&#8243; color_override=\u00bb#425cc7&#8243; hover_text_color_override=\u00bb#ffffff\u00bb icon_family=\u00bbnone\u00bb el_class=\u00bbbutton-dark-blue\u00bb url=\u00bb\/wp-content\/uploads\/2019\/12\/DOSSIER-NEVCCsp-1.pdf\u00bb text=\u00bbVer Dossier\u00bb][\/vc_column][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb2\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][image_with_animation image_url=\u00bb6495&#8243; animation=\u00bbNone\u00bb hover_animation=\u00bbnone\u00bb alignment=\u00bbcenter\u00bb img_link_target=\u00bb_blank\u00bb border_radius=\u00bbnone\u00bb box_shadow=\u00bbnone\u00bb image_loading=\u00bbdefault\u00bb max_width=\u00bb100%\u00bb max_width_mobile=\u00bbdefault\u00bb img_link=\u00bb\/wp-content\/uploads\/2019\/12\/DOSSIER-NEVCCsp-1.pdf\u00bb][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb60&#8243; bottom_padding=\u00bb40&#8243; text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overlay_strength=\u00bb0.3&#8243;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":6677,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-7093","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Leadership Excellence School<\/title>\n<meta name=\"description\" content=\"Especialistas en trabajar con profesionales, directivos, equipos, organizaciones y emprendedores para brindarles una gu\u00eda experta y creativa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nevcoaching.com\/es\/formacion\/leadership-excellence-school\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Leadership Excellence School\" \/>\n<meta property=\"og:description\" content=\"Especialistas en trabajar con profesionales, directivos, equipos, organizaciones y emprendedores para brindarles una gu\u00eda experta y creativa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nevcoaching.com\/es\/formacion\/leadership-excellence-school\/\" \/>\n<meta property=\"og:site_name\" content=\"NEV Coaching &amp; Consulting\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NevCoach\/\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-26T14:55:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nevcoaching.com\/wp-content\/uploads\/2022\/04\/Logo-NEV.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1607\" \/>\n\t<meta property=\"og:image:height\" content=\"1607\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@NevCoach\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/formacion\\\/leadership-excellence-school\\\/\",\"url\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/formacion\\\/leadership-excellence-school\\\/\",\"name\":\"Leadership Excellence School\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/#website\"},\"datePublished\":\"2019-07-03T16:34:10+00:00\",\"dateModified\":\"2021-10-26T14:55:14+00:00\",\"description\":\"Especialistas en trabajar con profesionales, directivos, equipos, organizaciones y emprendedores para brindarles una gu\u00eda experta y creativa.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/formacion\\\/leadership-excellence-school\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nevcoaching.com\\\/es\\\/formacion\\\/leadership-excellence-school\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/formacion\\\/leadership-excellence-school\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Formaci\u00f3n\",\"item\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/formacion\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Leadership Excellence School\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/\",\"name\":\"NEV Coaching &amp; Consulting\",\"description\":\"NEV Coaching &amp; Consulting\",\"publisher\":{\"@id\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/#organization\",\"name\":\"NEV Coaching & Consulting\",\"url\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nevcoaching.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Logo-NEV.png\",\"contentUrl\":\"https:\\\/\\\/nevcoaching.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Logo-NEV.png\",\"width\":1607,\"height\":1607,\"caption\":\"NEV Coaching & Consulting\"},\"image\":{\"@id\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NevCoach\\\/\",\"https:\\\/\\\/x.com\\\/NevCoach\",\"https:\\\/\\\/www.instagram.com\\\/nevcoach\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/nevcoach\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCiz77gnNFxgfOWAogmfjPGQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Leadership Excellence School","description":"Especialistas en trabajar con profesionales, directivos, equipos, organizaciones y emprendedores para brindarles una gu\u00eda experta y creativa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nevcoaching.com\/es\/formacion\/leadership-excellence-school\/","og_locale":"es_ES","og_type":"article","og_title":"Leadership Excellence School","og_description":"Especialistas en trabajar con profesionales, directivos, equipos, organizaciones y emprendedores para brindarles una gu\u00eda experta y creativa.","og_url":"https:\/\/nevcoaching.com\/es\/formacion\/leadership-excellence-school\/","og_site_name":"NEV Coaching &amp; Consulting","article_publisher":"https:\/\/www.facebook.com\/NevCoach\/","article_modified_time":"2021-10-26T14:55:14+00:00","og_image":[{"width":1607,"height":1607,"url":"https:\/\/nevcoaching.com\/wp-content\/uploads\/2022\/04\/Logo-NEV.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@NevCoach","twitter_misc":{"Tiempo de lectura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nevcoaching.com\/es\/formacion\/leadership-excellence-school\/","url":"https:\/\/nevcoaching.com\/es\/formacion\/leadership-excellence-school\/","name":"Leadership Excellence School","isPartOf":{"@id":"https:\/\/nevcoaching.com\/es\/#website"},"datePublished":"2019-07-03T16:34:10+00:00","dateModified":"2021-10-26T14:55:14+00:00","description":"Especialistas en trabajar con profesionales, directivos, equipos, organizaciones y emprendedores para brindarles una gu\u00eda experta y creativa.","breadcrumb":{"@id":"https:\/\/nevcoaching.com\/es\/formacion\/leadership-excellence-school\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nevcoaching.com\/es\/formacion\/leadership-excellence-school\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nevcoaching.com\/es\/formacion\/leadership-excellence-school\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/nevcoaching.com\/es\/"},{"@type":"ListItem","position":2,"name":"Formaci\u00f3n","item":"https:\/\/nevcoaching.com\/es\/formacion\/"},{"@type":"ListItem","position":3,"name":"Leadership Excellence School"}]},{"@type":"WebSite","@id":"https:\/\/nevcoaching.com\/es\/#website","url":"https:\/\/nevcoaching.com\/es\/","name":"NEV Coaching &amp; Consulting","description":"NEV Coaching &amp; Consulting","publisher":{"@id":"https:\/\/nevcoaching.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nevcoaching.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/nevcoaching.com\/es\/#organization","name":"NEV Coaching & Consulting","url":"https:\/\/nevcoaching.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nevcoaching.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/nevcoaching.com\/wp-content\/uploads\/2022\/04\/Logo-NEV.png","contentUrl":"https:\/\/nevcoaching.com\/wp-content\/uploads\/2022\/04\/Logo-NEV.png","width":1607,"height":1607,"caption":"NEV Coaching & Consulting"},"image":{"@id":"https:\/\/nevcoaching.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NevCoach\/","https:\/\/x.com\/NevCoach","https:\/\/www.instagram.com\/nevcoach\/","https:\/\/www.linkedin.com\/in\/nevcoach\/","https:\/\/www.youtube.com\/channel\/UCiz77gnNFxgfOWAogmfjPGQ"]}]}},"_links":{"self":[{"href":"https:\/\/nevcoaching.com\/es\/wp-json\/wp\/v2\/pages\/7093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nevcoaching.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nevcoaching.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nevcoaching.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nevcoaching.com\/es\/wp-json\/wp\/v2\/comments?post=7093"}],"version-history":[{"count":7,"href":"https:\/\/nevcoaching.com\/es\/wp-json\/wp\/v2\/pages\/7093\/revisions"}],"predecessor-version":[{"id":11635,"href":"https:\/\/nevcoaching.com\/es\/wp-json\/wp\/v2\/pages\/7093\/revisions\/11635"}],"up":[{"embeddable":true,"href":"https:\/\/nevcoaching.com\/es\/wp-json\/wp\/v2\/pages\/6677"}],"wp:attachment":[{"href":"https:\/\/nevcoaching.com\/es\/wp-json\/wp\/v2\/media?parent=7093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}