{"id":10681,"date":"2021-02-16T14:00:56","date_gmt":"2021-02-16T13:00:56","guid":{"rendered":"https:\/\/nevcoaching.com\/?p=10681"},"modified":"2021-04-09T19:46:26","modified_gmt":"2021-04-09T17:46:26","slug":"estas-tan-ocupado-pero-y-si-no-fuera-necesario","status":"publish","type":"post","link":"https:\/\/nevcoaching.com\/es\/estas-tan-ocupado-pero-y-si-no-fuera-necesario\/","title":{"rendered":"\u00a1Est\u00e1s TAN OCUPADO! Pero, \u00bfy si no fuera necesario?"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-10797 alignleft\" src=\"https:\/\/nevcoaching.com\/wp-content\/uploads\/2021\/02\/BLUESIZEben-white-xqjMjaGGhmw-unsplash-3-300x200.jpg\" alt=\"ocupado\" width=\"300\" height=\"200\" srcset=\"https:\/\/nevcoaching.com\/wp-content\/uploads\/2021\/02\/BLUESIZEben-white-xqjMjaGGhmw-unsplash-3-300x200.jpg 300w, https:\/\/nevcoaching.com\/wp-content\/uploads\/2021\/02\/BLUESIZEben-white-xqjMjaGGhmw-unsplash-3-1024x684.jpg 1024w, https:\/\/nevcoaching.com\/wp-content\/uploads\/2021\/02\/BLUESIZEben-white-xqjMjaGGhmw-unsplash-3-768x513.jpg 768w, https:\/\/nevcoaching.com\/wp-content\/uploads\/2021\/02\/BLUESIZEben-white-xqjMjaGGhmw-unsplash-3-1536x1026.jpg 1536w, https:\/\/nevcoaching.com\/wp-content\/uploads\/2021\/02\/BLUESIZEben-white-xqjMjaGGhmw-unsplash-3-900x600.jpg 900w, https:\/\/nevcoaching.com\/wp-content\/uploads\/2021\/02\/BLUESIZEben-white-xqjMjaGGhmw-unsplash-3.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Est\u00e1s REALMENTE ocupado. Quiz\u00e1s incluso est\u00e1s abrumado. TE ENTIENDO.<\/strong><\/p>\n<p>Yo he estado ah\u00ed. S\u00e9 la agon\u00eda que es estar absolutamente exhausto, saturado y harto de todo lo que exige tu atenci\u00f3n y cuidado.<\/p>\n<p>As\u00ed que esta publicaci\u00f3n es para TI.<\/p>\n<h3><span style=\"color: #333333;\"><strong>No se trata de hacerte SENTIR MAL por estar ocupado. \u00a1NUNCA!<\/strong><\/span><\/h3>\n<p>Se trata de aportar una nueva luz a esta compleja ecuaci\u00f3n, que es tu vida y tu trabajo.<\/p>\n<p><strong>Cambiar tu perspectiva, tus creencias y tus elecciones, puede crear una mejor calidad de vida, para ti y los tuyos. AHORA.<\/strong><\/p>\n<p>Y para demostrarlo, contamos con m\u00e1s de una d\u00e9cada de resultados comprobados y avances positivos en esta \u00e1rea. Personal y profesionalmente hablando.<\/p>\n<p>Los cambios iniciales pueden parecer dif\u00edciles, pero una vez que empiezas, es MUCHO m\u00e1s f\u00e1cil.<\/p>\n<p>Te preguntar\u00e1s c\u00f3mo pudiste sobrevivir antes.<\/p>\n<p>&nbsp;<\/p>\n<p>Aqu\u00ed hay algunas ideas y preguntas para tener en cuenta y trabajar hacia una vida y un trabajo m\u00e1s F\u00c1CIL:<\/p>\n<h2><span style=\"color: #333333;\"><strong>Esto te ayudar\u00e1 a dejar de estar tan ocupado<\/strong><\/span><span style=\"color: #333333;\"><strong>.<\/strong><\/span><\/h2>\n<h3><strong>1) \u00bfDe verdad conoces TODO tu UNIVERSO DE RESPONSABILIDAD?<\/strong><\/h3>\n<p>Aqu\u00ed hay una de las primeras cosas que pedimos a nuestros clientes y hacemos nosotros mismos. <strong>Crear un MindMap (Mapa Mental) detallado de TODAS tus responsabilidades. Todo lo que est\u00e1s gestionando actualmente<\/strong> <strong>en tu vida, personal y profesionalmente.<\/strong><\/p>\n<p>La clave es hacerlo lo m\u00e1s DETALLADO posible. Incluso hasta tres niveles de subtareas por cada \u00e1rea principal.<\/p>\n<p>Casi todo el mundo lucha con este ejercicio al principio. Hay algunos incluso que me odian por ello, pero TODOS obtienen informaci\u00f3n y resultados INCRE\u00cdBLES.<\/p>\n<p>Y una vez que obtengas la primera versi\u00f3n, las futuras son MUCHO M\u00c1S F\u00c1CILES de actualizar.<\/p>\n<p><strong>La clave es comprender que: para reflexionar sobre tu carga de trabajo actual, primero debes comprender claramente cual es.<\/strong><\/p>\n<p>No importa cu\u00e1nto creas que lo tienes claro en tu cabeza. En el papel, liberar\u00e1 enormemente tu espacio mental para pensar y analizar mejor. Y aqu\u00ed es de donde vienen las grandes soluciones para un alivio y LIBERTAD renovados.<\/p>\n<p>Si quieres algo de <span style=\"color: #333333;\"><strong>orientaci\u00f3n sobre como crear una Mapa Mental efectivo<\/strong><\/span>, <span style=\"color: #425cc7;\"><a style=\"color: #425cc7;\" href=\"https:\/\/nevcoaching.com\/es\/acerca-de\/contactenos\/\" target=\"_blank\" rel=\"noopener\"><strong>cont\u00e1ctame para una consulta gratuita<\/strong><\/a><\/span> y con gusto te ense\u00f1ar\u00e9.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>2) Cualquier cosa que eliges hacer es, esencialmente, una ELECCI\u00d3N.<\/strong><\/h3>\n<p>Incluso si es dif\u00edcil. O una ocupaci\u00f3n con la que te hayas comprometido hace mucho tiempo. Quiz\u00e1s incluso una a la que est\u00e1s tan acostumbrado que no puedes ni imaginar no hacerla. Una a la que tienes miedo de dejar ir, incluso cuando est\u00e1s tan cansado de ella.<\/p>\n<p>Pero es una elecci\u00f3n.<\/p>\n<p><strong>Esto puede parecer injusto, pero es una declaraci\u00f3n importante y una VERDAD. Muy pocas cosas en nuestras vidas (QU\u00c9 hacemos y C\u00d3MO lo hacemos) en realidad, tienen que continuar exactamente igual.<\/strong><\/p>\n<p>Los peque\u00f1os cambios pueden crear hitos asombrosos para una mayor facilidad, alivio y liberaci\u00f3n.<\/p>\n<h3><span style=\"color: #333333;\">La pregunta es:<\/span> <strong>\u00bfest\u00e1s dispuesto a echar un vistazo y cuestionar las decisiones que te mantienen tan ocupado?<\/strong><\/h3>\n<p>Muchas personas dir\u00e1n que s\u00ed a esto. Pero en la pr\u00e1ctica luchar\u00e1n con u\u00f1as y dientes para defender las mismas cosas que les hacen da\u00f1o.<\/p>\n<p>Y lo entiendo: algunas cosas TIENEN que continuar, de una forma u otra.<\/p>\n<p>Pero si el resultado es UN ALIVIO ENORME para ti y los tuyos, \u00bfno vale la pena echarle un vistazo?<\/p>\n<p>\u00bfHaci\u00e9ndote una pregunta?<\/p>\n<p>\u00bfCambiando el paradigma?<\/p>\n<p>Solo t\u00fa puedes decidir.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>3) \u00bfConoces tus PRIORIDADES? \u00bfSon tuyas o de los dem\u00e1s?<\/strong><\/h3>\n<p>Si consideras ahora los puntos 1) y 2), la siguiente pregunta l\u00f3gica es:<\/p>\n<p><strong>\u201c\u00bfQu\u00e9 es realmente importante para ti?\u201d<\/strong><\/p>\n<p>Siempre nos lo preguntamos, a nosotros mismos y a todas las personas con las que trabajamos.<\/p>\n<p><strong>La realidad es que NO PUEDES HACERLO TODO.<\/strong> Porque las cosas importantes en tu vida merecen respeto, concentraci\u00f3n, energ\u00eda e inversi\u00f3n para hacerlas efectivas.<\/p>\n<p>Y la clave para la m\u00e1xima productividad y eficacia es entender que \u201cpara decir S\u00cd a determinadas cosas, tambi\u00e9n tienes que decir NO a muchas otras\u201d.<\/p>\n<p><strong>No existe una f\u00f3rmula m\u00e1gica que te permita expandirte y as\u00ed hacer todo de manera excelente. Tienes que elegir.<\/strong><\/p>\n<p>La mejor manera de comenzar es limpiar tu \u201clista\u201d de tareas y simplemente escribir una lista de aquellas que son realmente las m\u00e1s importantes para ti y que realmente requieren que las hagas T\u00da (en lugar de alguien m\u00e1s que pueda ayudar).<\/p>\n<p>Luego ves a tu MindMap que representa todo tu Universo de Responsabilidades y eliges un n\u00famero razonable de subtareas espec\u00edficas a las que puedas dedicarte adecuadamente en la pr\u00f3xima temporada.<\/p>\n<p>S\u00ed, SUBTAREAS, no \u00e1reas centrales.<\/p>\n<p>Por peque\u00f1as que parezcan, cada responsabilidad requiere una inversi\u00f3n, de la cual tienes una cantidad limitada. No importa cu\u00e1n eficiente, efectivo y supermotivado est\u00e9s.<\/p>\n<p>La cantidad que puedes administrar de manera efectiva y saludable puede ser mayor que para otros, pero a\u00fan as\u00ed no es ilimitada.<\/p>\n<p>Cuanto antes respetes e incluso celebres eso, m\u00e1s f\u00e1cil ser\u00e1 DECIR S\u00cd a lo que realmente importa y delegar, retrasar o incluso eliminar el resto.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>4) Decir NO es la CLAVE para LIBERAR una vida ocupada.<\/strong><\/h3>\n<p>Esto puede parecer una traici\u00f3n. Decir que no &#8230;a algo que quieres hacer, sientes que tienes que hacer, a otros que dependen de ti, etc.<\/p>\n<p>Pero como parafraseo de un <span style=\"color: #425cc7;\"><strong><a style=\"color: #425cc7;\" href=\"https:\/\/richlitvin.com\/no\/\" target=\"_blank\" rel=\"noopener\">blog reciente del famoso coach Rich Litvin<\/a><\/strong><\/span>: <strong>\u201dten\u00edas que decir S\u00cd a muchas cosas para obtener tu experiencia y respeto. Pero despu\u00e9s, tienes que decir NO a muchas cosas para tener \u00c9XITO\u201d<\/strong>.<\/p>\n<p>Y como cita \u00e9l poderosamente, el propio Warren Buffet dijo: <span style=\"color: #425cc7;\"><strong>\u201c<a style=\"color: #425cc7;\" href=\"https:\/\/www.inc.com\/marcel-schwantes\/warren-buffett-says-this-is-1-simple-habit-that-separates-successful-people-from-everyone-else.html\" target=\"_blank\" rel=\"noopener\">Las personas exitosas dicen NO a casi todo<\/a>\u201d<\/strong><\/span>.<\/p>\n<p>\u00bfQU\u00c9? De Verdad?<\/p>\n<p>Si.<\/p>\n<p>Cuanto m\u00e1s crece Tu Universo, m\u00e1s creces tu mismo y m\u00e1s personas y cosas exigir\u00e1n tu atenci\u00f3n y esfuerzo.<\/p>\n<p>Entonces, practicar de manera respetuosa y efectiva decir NO a las cosas, ser\u00e1 la clave para tu nueva libertad y \u00e9xito.<\/p>\n<p>No tienes que justificarte ni disculparte.<\/p>\n<p>Solo da la suficiente informaci\u00f3n para que sea significativo y eso es suficiente.<\/p>\n<p>Puede sonar as\u00ed:<\/p>\n<p>\u201cGracias por esta invitaci\u00f3n \/ oportunidad \/ consulta. En este momento, ya tengo prioridades esenciales en el trabajo \/ salud \/ familia \/ etc. que requieren mi mejor compromiso y no puedo atender m\u00e1s. Pero lo considerar\u00e9 en el futuro (si lo deseas) y te deseo un gran \u00e9xito en tu iniciativa.\u201d<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>5) Tu \u00f3ptimo es en realidad el 70%, no el <\/strong><strong>poco realista <\/strong><strong>100%.<\/strong><\/h3>\n<p>Scott Jeffrey en una publicaci\u00f3n reciente habl\u00f3 sobre la moderaci\u00f3n, <span style=\"color: #425cc7;\"><strong><a style=\"color: #425cc7;\" href=\"https:\/\/scottjeffrey.com\/middle-way\/\" target=\"_blank\" rel=\"noopener\">el Camino del Medio<\/a><\/strong><\/span>. Y de c\u00f3mo, si realmente pensamos de manera realista, no podemos dar el 100% a nada.<\/p>\n<p>\u00bfPor qu\u00e9?<\/p>\n<p>Porque nuestro 100% debe extenderse a TODAS las cosas m\u00e1s importantes de las que somos responsables y tenemos que gestionar.<\/p>\n<p>Si dedicamos el 100% a solo un tema, dejamos de respetar los l\u00edmites saludables y realistas de nuestro tiempo, recursos y bienestar.<\/p>\n<p>\u00bfY el resultado? Abrumador agotamiento, sobrecarga, frustraci\u00f3n, enfado, desmotivaci\u00f3n, etc.<\/p>\n<p><strong>S\u00ed, hay momentos en los que todos necesitamos EXCEDERNOS: per\u00edodos que nos obligan a esforzarnos intensamente para conseguir grandes logros, superar momentos dif\u00edciles, gestionar m\u00e1s de lo razonable, etc.<\/strong><\/p>\n<p><strong>Est\u00e1 bien. Pero no deber\u00eda ser tu D\u00cdA a D\u00cdA.<\/strong><\/p>\n<p>Si lo piensas, tienes una gran capacidad. Y el 70% de esa gran capacidad es en realidad MUCHA.<\/p>\n<p>Entonces,<strong> \u00bfcu\u00e1nto m\u00e1s placentera, productiva y efectiva ser\u00eda tu existencia si estuvieras apuntando a una s\u00f3lida inversi\u00f3n del 70% en cualquier cosa que hagas?<\/strong><\/p>\n<p>Versus insistir en m\u00e1s y pagar el precio.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>6) \u00bfQu\u00e9 significa realmente para ti <\/strong><strong>\u201c<\/strong><strong>estar TAN OCUPADO<\/strong><strong>\u201d<\/strong><strong>?<\/strong><\/h3>\n<p>Algunas personas se burlar\u00e1n de esta pregunta porque sienten que no tienen otra opci\u00f3n m\u00e1s que seguir tan saturadas. Y ese puede ser tu caso, o no.<\/p>\n<p><strong>Pero todav\u00eda hay muchas personas que adquieren un sentido de importancia, evidencia personal y justificaci\u00f3n de su valor, al \u201cdemostrar\u201d que son \u201cpersonas realmente ocupadas\u201d.<\/strong><\/p>\n<p>Yo sol\u00eda ser una de ellas. Hace un tiempo sent\u00ed que, si no estaba realmente ocupada, no estaba haciendo lo suficiente.<\/p>\n<p>De hecho, SUPEROCUPADA era mi pan de cada d\u00eda desde que era una ni\u00f1a peque\u00f1a (con innumerables compromisos fuera de la escuela m\u00e1s las tareas del hogar). <strong>No SENT\u00cdA que estaba haciendo lo suficiente, dando lo suficiente, a menos que sintiera el DOLOR y el esfuerzo de empujar m\u00e1s all\u00e1 de mis l\u00edmites.<\/strong><\/p>\n<p>\u00bf\u00bfQu\u00e9??<\/p>\n<p>\u00bfD\u00f3nde aprendimos eso?<\/p>\n<p>Pues muchos de nosotros lo hicimos. Y allan\u00f3 el camino para una existencia que te hace sentir que \u201cnunca eres suficiente\u201d.<\/p>\n<p>\u201cNunca ES suficiente\u201d.<\/p>\n<p>\u201cA menos que sienta que no puedo hacer, sentir, pensar en nada m\u00e1s\u201d.<\/p>\n<p>No es de extra\u00f1ar que tengamos dificultades para descansar, relajarnos, desconectarnos y disfrutar.<\/p>\n<p>Puedes profundizar sobre eso en nuestra publicaci\u00f3n anterior: <span style=\"color: #425cc7;\"><strong><span style=\"color: #425cc7;\">\u201c<a style=\"color: #425cc7;\" href=\"https:\/\/nevcoaching.com\/es\/no-soy-suficiente\/\">No soy suficiente<\/a>\u201d.<\/span><\/strong><\/span><\/p>\n<h4><strong>Pero nuestra vida est\u00e1 destinada a ser m\u00e1s que una acumulaci\u00f3n de tareas para hacernos sentir importantes.<\/strong><\/h4>\n<p><strong>Somos suficientes tal como somos. <\/strong><\/p>\n<p>Y encontrando formas de apreciar esto y celebrando TODOS los momentos que esta vida tiene para ofrecer, es cuando el verdadero significado llega a nuestra vida diaria.<\/p>\n<p>&nbsp;<\/p>\n<p>Como siempre, no dudes en contactarnos con tus pensamientos y preguntas. Env\u00edanos tus ideas sobre c\u00f3mo te est\u00e1s transformando de OCUPADO a EQUILIBRADO.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Est\u00e1s REALMENTE ocupado. Quiz\u00e1s incluso est\u00e1s abrumado. TE ENTIENDO. Yo he estado ah\u00ed. S\u00e9 la&#8230;<\/p>\n","protected":false},"author":4,"featured_media":10797,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[37,34,35],"tags":[533,83,232,281,256,215,216,218,535,547,220,545,221,223,548,282,537,538,539,540,541,544,546,543],"class_list":{"0":"post-10681","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-ama-a-tu-trabajo","8":"category-innovacion-personal","9":"category-paz-y-felicidad","10":"tag-burnout-es","11":"tag-business-coaching","12":"tag-cambios-positivos","13":"tag-carrera-profesional","14":"tag-coaching-valencia","15":"tag-confianza","16":"tag-desarrollo-personal","17":"tag-desarrollo-profesional","18":"tag-ease-es","19":"tag-efectividad","20":"tag-equilibrio-vida-trabajo","21":"tag-estresado","22":"tag-exito","23":"tag-gestion-de-estres","24":"tag-gestion-del-tiempo","25":"tag-objetivos","26":"tag-organization-es","27":"tag-overwhelm-es","28":"tag-peace-of-mind-es","29":"tag-personal-effectiveness-es","30":"tag-productivity-es","31":"tag-quemado","32":"tag-saturado","33":"tag-self-management-es"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00a1Est\u00e1s TAN OCUPADO! Pero, \u00bfy si no fuera necesario? - NEV C&amp;C<\/title>\n<meta name=\"description\" content=\"Est\u00e1s REALMENTE ocupado. Quiz\u00e1s incluso est\u00e1s abrumado. Lo se, TE ENTIENDO. Pero, \u00bfy si pudieras dejar de estar tan ocupado?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nevcoaching.com\/es\/estas-tan-ocupado-pero-y-si-no-fuera-necesario\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1Est\u00e1s TAN OCUPADO! Pero, \u00bfy si no fuera necesario? - NEV C&amp;C\" \/>\n<meta property=\"og:description\" content=\"Est\u00e1s REALMENTE ocupado. Quiz\u00e1s incluso est\u00e1s abrumado. Lo se, TE ENTIENDO. Pero, \u00bfy si pudieras dejar de estar tan ocupado?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nevcoaching.com\/es\/estas-tan-ocupado-pero-y-si-no-fuera-necesario\/\" \/>\n<meta property=\"og:site_name\" content=\"NEV Coaching &amp; Consulting\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NevCoach\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-16T13:00:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-09T17:46:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nevcoaching.com\/wp-content\/uploads\/2021\/02\/BLUESIZEben-white-xqjMjaGGhmw-unsplash-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1282\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nevena Vujosevic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NevCoach\" \/>\n<meta name=\"twitter:site\" content=\"@NevCoach\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nevena Vujosevic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/estas-tan-ocupado-pero-y-si-no-fuera-necesario\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/estas-tan-ocupado-pero-y-si-no-fuera-necesario\\\/\"},\"author\":{\"name\":\"Nevena Vujosevic\",\"@id\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/#\\\/schema\\\/person\\\/58e5f24b63283f3ddeb32586781fbb7f\"},\"headline\":\"\u00a1Est\u00e1s TAN OCUPADO! Pero, \u00bfy si no fuera necesario?\",\"datePublished\":\"2021-02-16T13:00:56+00:00\",\"dateModified\":\"2021-04-09T17:46:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/estas-tan-ocupado-pero-y-si-no-fuera-necesario\\\/\"},\"wordCount\":1585,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/estas-tan-ocupado-pero-y-si-no-fuera-necesario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nevcoaching.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/BLUESIZEben-white-xqjMjaGGhmw-unsplash-3.jpg\",\"keywords\":[\"burnout\",\"business coaching\",\"cambios positivos\",\"carrera profesional\",\"coaching Valencia\",\"confianza\",\"desarrollo personal\",\"desarrollo profesional\",\"ease\",\"efectividad\",\"equilibrio vida-trabajo\",\"estresado\",\"exito\",\"gestion de estres\",\"gesti\u00f3n del tiempo\",\"objetivos\",\"organization\",\"overwhelm\",\"peace of mind\",\"personal effectiveness\",\"productivity\",\"quemado\",\"saturado\",\"self-management\"],\"articleSection\":[\"Ama a Tu Trabajo\",\"Innovaci\u00f3n Personal\",\"Paz &amp; Felicidad\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/nevcoaching.com\\\/es\\\/estas-tan-ocupado-pero-y-si-no-fuera-necesario\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/estas-tan-ocupado-pero-y-si-no-fuera-necesario\\\/\",\"url\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/estas-tan-ocupado-pero-y-si-no-fuera-necesario\\\/\",\"name\":\"\u00a1Est\u00e1s TAN OCUPADO! Pero, \u00bfy si no fuera necesario? - NEV C&C\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/estas-tan-ocupado-pero-y-si-no-fuera-necesario\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/estas-tan-ocupado-pero-y-si-no-fuera-necesario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nevcoaching.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/BLUESIZEben-white-xqjMjaGGhmw-unsplash-3.jpg\",\"datePublished\":\"2021-02-16T13:00:56+00:00\",\"dateModified\":\"2021-04-09T17:46:26+00:00\",\"description\":\"Est\u00e1s REALMENTE ocupado. Quiz\u00e1s incluso est\u00e1s abrumado. Lo se, TE ENTIENDO. Pero, \u00bfy si pudieras dejar de estar tan ocupado?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/estas-tan-ocupado-pero-y-si-no-fuera-necesario\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nevcoaching.com\\\/es\\\/estas-tan-ocupado-pero-y-si-no-fuera-necesario\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/estas-tan-ocupado-pero-y-si-no-fuera-necesario\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nevcoaching.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/BLUESIZEben-white-xqjMjaGGhmw-unsplash-3.jpg\",\"contentUrl\":\"https:\\\/\\\/nevcoaching.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/BLUESIZEben-white-xqjMjaGGhmw-unsplash-3.jpg\",\"width\":1920,\"height\":1282,\"caption\":\"ocupado\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/estas-tan-ocupado-pero-y-si-no-fuera-necesario\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a1Est\u00e1s TAN OCUPADO! Pero, \u00bfy si no fuera necesario?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/\",\"name\":\"NEV Coaching &amp; Consulting\",\"description\":\"NEV Coaching &amp; Consulting\",\"publisher\":{\"@id\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/#organization\",\"name\":\"NEV Coaching & Consulting\",\"url\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nevcoaching.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Logo-NEV.png\",\"contentUrl\":\"https:\\\/\\\/nevcoaching.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Logo-NEV.png\",\"width\":1607,\"height\":1607,\"caption\":\"NEV Coaching & Consulting\"},\"image\":{\"@id\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NevCoach\\\/\",\"https:\\\/\\\/x.com\\\/NevCoach\",\"https:\\\/\\\/www.instagram.com\\\/nevcoach\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/nevcoach\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCiz77gnNFxgfOWAogmfjPGQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/#\\\/schema\\\/person\\\/58e5f24b63283f3ddeb32586781fbb7f\",\"name\":\"Nevena Vujosevic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12cf0dda221d5804fa0b875c1cf6149c333fe03cd4f80595d04077b7219dc034?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12cf0dda221d5804fa0b875c1cf6149c333fe03cd4f80595d04077b7219dc034?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12cf0dda221d5804fa0b875c1cf6149c333fe03cd4f80595d04077b7219dc034?s=96&d=mm&r=g\",\"caption\":\"Nevena Vujosevic\"},\"url\":\"https:\\\/\\\/nevcoaching.com\\\/es\\\/author\\\/monica\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1Est\u00e1s TAN OCUPADO! Pero, \u00bfy si no fuera necesario? - NEV C&C","description":"Est\u00e1s REALMENTE ocupado. Quiz\u00e1s incluso est\u00e1s abrumado. Lo se, TE ENTIENDO. Pero, \u00bfy si pudieras dejar de estar tan ocupado?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nevcoaching.com\/es\/estas-tan-ocupado-pero-y-si-no-fuera-necesario\/","og_locale":"es_ES","og_type":"article","og_title":"\u00a1Est\u00e1s TAN OCUPADO! Pero, \u00bfy si no fuera necesario? - NEV C&C","og_description":"Est\u00e1s REALMENTE ocupado. Quiz\u00e1s incluso est\u00e1s abrumado. Lo se, TE ENTIENDO. Pero, \u00bfy si pudieras dejar de estar tan ocupado?","og_url":"https:\/\/nevcoaching.com\/es\/estas-tan-ocupado-pero-y-si-no-fuera-necesario\/","og_site_name":"NEV Coaching &amp; Consulting","article_publisher":"https:\/\/www.facebook.com\/NevCoach\/","article_published_time":"2021-02-16T13:00:56+00:00","article_modified_time":"2021-04-09T17:46:26+00:00","og_image":[{"width":1920,"height":1282,"url":"https:\/\/nevcoaching.com\/wp-content\/uploads\/2021\/02\/BLUESIZEben-white-xqjMjaGGhmw-unsplash-3.jpg","type":"image\/jpeg"}],"author":"Nevena Vujosevic","twitter_card":"summary_large_image","twitter_creator":"@NevCoach","twitter_site":"@NevCoach","twitter_misc":{"Escrito por":"Nevena Vujosevic","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nevcoaching.com\/es\/estas-tan-ocupado-pero-y-si-no-fuera-necesario\/#article","isPartOf":{"@id":"https:\/\/nevcoaching.com\/es\/estas-tan-ocupado-pero-y-si-no-fuera-necesario\/"},"author":{"name":"Nevena Vujosevic","@id":"https:\/\/nevcoaching.com\/es\/#\/schema\/person\/58e5f24b63283f3ddeb32586781fbb7f"},"headline":"\u00a1Est\u00e1s TAN OCUPADO! Pero, \u00bfy si no fuera necesario?","datePublished":"2021-02-16T13:00:56+00:00","dateModified":"2021-04-09T17:46:26+00:00","mainEntityOfPage":{"@id":"https:\/\/nevcoaching.com\/es\/estas-tan-ocupado-pero-y-si-no-fuera-necesario\/"},"wordCount":1585,"commentCount":0,"publisher":{"@id":"https:\/\/nevcoaching.com\/es\/#organization"},"image":{"@id":"https:\/\/nevcoaching.com\/es\/estas-tan-ocupado-pero-y-si-no-fuera-necesario\/#primaryimage"},"thumbnailUrl":"https:\/\/nevcoaching.com\/wp-content\/uploads\/2021\/02\/BLUESIZEben-white-xqjMjaGGhmw-unsplash-3.jpg","keywords":["burnout","business coaching","cambios positivos","carrera profesional","coaching Valencia","confianza","desarrollo personal","desarrollo profesional","ease","efectividad","equilibrio vida-trabajo","estresado","exito","gestion de estres","gesti\u00f3n del tiempo","objetivos","organization","overwhelm","peace of mind","personal effectiveness","productivity","quemado","saturado","self-management"],"articleSection":["Ama a Tu Trabajo","Innovaci\u00f3n Personal","Paz &amp; Felicidad"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/nevcoaching.com\/es\/estas-tan-ocupado-pero-y-si-no-fuera-necesario\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/nevcoaching.com\/es\/estas-tan-ocupado-pero-y-si-no-fuera-necesario\/","url":"https:\/\/nevcoaching.com\/es\/estas-tan-ocupado-pero-y-si-no-fuera-necesario\/","name":"\u00a1Est\u00e1s TAN OCUPADO! Pero, \u00bfy si no fuera necesario? - NEV C&C","isPartOf":{"@id":"https:\/\/nevcoaching.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nevcoaching.com\/es\/estas-tan-ocupado-pero-y-si-no-fuera-necesario\/#primaryimage"},"image":{"@id":"https:\/\/nevcoaching.com\/es\/estas-tan-ocupado-pero-y-si-no-fuera-necesario\/#primaryimage"},"thumbnailUrl":"https:\/\/nevcoaching.com\/wp-content\/uploads\/2021\/02\/BLUESIZEben-white-xqjMjaGGhmw-unsplash-3.jpg","datePublished":"2021-02-16T13:00:56+00:00","dateModified":"2021-04-09T17:46:26+00:00","description":"Est\u00e1s REALMENTE ocupado. Quiz\u00e1s incluso est\u00e1s abrumado. Lo se, TE ENTIENDO. Pero, \u00bfy si pudieras dejar de estar tan ocupado?","breadcrumb":{"@id":"https:\/\/nevcoaching.com\/es\/estas-tan-ocupado-pero-y-si-no-fuera-necesario\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nevcoaching.com\/es\/estas-tan-ocupado-pero-y-si-no-fuera-necesario\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nevcoaching.com\/es\/estas-tan-ocupado-pero-y-si-no-fuera-necesario\/#primaryimage","url":"https:\/\/nevcoaching.com\/wp-content\/uploads\/2021\/02\/BLUESIZEben-white-xqjMjaGGhmw-unsplash-3.jpg","contentUrl":"https:\/\/nevcoaching.com\/wp-content\/uploads\/2021\/02\/BLUESIZEben-white-xqjMjaGGhmw-unsplash-3.jpg","width":1920,"height":1282,"caption":"ocupado"},{"@type":"BreadcrumbList","@id":"https:\/\/nevcoaching.com\/es\/estas-tan-ocupado-pero-y-si-no-fuera-necesario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/nevcoaching.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u00a1Est\u00e1s TAN OCUPADO! Pero, \u00bfy si no fuera necesario?"}]},{"@type":"WebSite","@id":"https:\/\/nevcoaching.com\/es\/#website","url":"https:\/\/nevcoaching.com\/es\/","name":"NEV Coaching &amp; Consulting","description":"NEV Coaching &amp; Consulting","publisher":{"@id":"https:\/\/nevcoaching.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nevcoaching.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/nevcoaching.com\/es\/#organization","name":"NEV Coaching & Consulting","url":"https:\/\/nevcoaching.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nevcoaching.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/nevcoaching.com\/wp-content\/uploads\/2022\/04\/Logo-NEV.png","contentUrl":"https:\/\/nevcoaching.com\/wp-content\/uploads\/2022\/04\/Logo-NEV.png","width":1607,"height":1607,"caption":"NEV Coaching & Consulting"},"image":{"@id":"https:\/\/nevcoaching.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NevCoach\/","https:\/\/x.com\/NevCoach","https:\/\/www.instagram.com\/nevcoach\/","https:\/\/www.linkedin.com\/in\/nevcoach\/","https:\/\/www.youtube.com\/channel\/UCiz77gnNFxgfOWAogmfjPGQ"]},{"@type":"Person","@id":"https:\/\/nevcoaching.com\/es\/#\/schema\/person\/58e5f24b63283f3ddeb32586781fbb7f","name":"Nevena Vujosevic","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/12cf0dda221d5804fa0b875c1cf6149c333fe03cd4f80595d04077b7219dc034?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/12cf0dda221d5804fa0b875c1cf6149c333fe03cd4f80595d04077b7219dc034?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/12cf0dda221d5804fa0b875c1cf6149c333fe03cd4f80595d04077b7219dc034?s=96&d=mm&r=g","caption":"Nevena Vujosevic"},"url":"https:\/\/nevcoaching.com\/es\/author\/monica\/"}]}},"_links":{"self":[{"href":"https:\/\/nevcoaching.com\/es\/wp-json\/wp\/v2\/posts\/10681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nevcoaching.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nevcoaching.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nevcoaching.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/nevcoaching.com\/es\/wp-json\/wp\/v2\/comments?post=10681"}],"version-history":[{"count":25,"href":"https:\/\/nevcoaching.com\/es\/wp-json\/wp\/v2\/posts\/10681\/revisions"}],"predecessor-version":[{"id":10800,"href":"https:\/\/nevcoaching.com\/es\/wp-json\/wp\/v2\/posts\/10681\/revisions\/10800"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nevcoaching.com\/es\/wp-json\/wp\/v2\/media\/10797"}],"wp:attachment":[{"href":"https:\/\/nevcoaching.com\/es\/wp-json\/wp\/v2\/media?parent=10681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nevcoaching.com\/es\/wp-json\/wp\/v2\/categories?post=10681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nevcoaching.com\/es\/wp-json\/wp\/v2\/tags?post=10681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}